{"id":100,"count":2,"description":"","link":"https:\/\/www.patrick-koglin.com\/en\/category\/gesetz-der-anziehung\/","name":"Gesetz der Anziehung","slug":"gesetz-der-anziehung","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gesetz der Anziehung Archive - Patrick Koglin<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.patrick-koglin.com\/en\/category\/gesetz-der-anziehung\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gesetz der Anziehung Archive - Patrick Koglin\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.patrick-koglin.com\/en\/category\/gesetz-der-anziehung\/\" \/>\n<meta property=\"og:site_name\" content=\"Patrick Koglin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.patrick-koglin.com\/category\/gesetz-der-anziehung\/\",\"url\":\"https:\/\/www.patrick-koglin.com\/category\/gesetz-der-anziehung\/\",\"name\":\"Gesetz der Anziehung Archive - Patrick Koglin\",\"isPartOf\":{\"@id\":\"https:\/\/www.patrick-koglin.com\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.patrick-koglin.com\/category\/gesetz-der-anziehung\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.patrick-koglin.com\/category\/gesetz-der-anziehung\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.patrick-koglin.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gesetz der Anziehung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.patrick-koglin.com\/#website\",\"url\":\"https:\/\/www.patrick-koglin.com\/\",\"name\":\"PK Coaching - Patrick Koglin Unternehmensgruppe\",\"description\":\"PK Coaching, Business-Design &amp; Development\",\"publisher\":{\"@id\":\"https:\/\/www.patrick-koglin.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.patrick-koglin.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.patrick-koglin.com\/#organization\",\"name\":\"Patrick Koglin | CEO von PK Coaching\",\"url\":\"https:\/\/www.patrick-koglin.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.patrick-koglin.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.patrick-koglin.com\/wp-content\/uploads\/2025\/07\/cropped-PK16.png\",\"contentUrl\":\"https:\/\/www.patrick-koglin.com\/wp-content\/uploads\/2025\/07\/cropped-PK16.png\",\"width\":619,\"height\":287,\"caption\":\"Patrick Koglin | CEO von PK Coaching\"},\"image\":{\"@id\":\"https:\/\/www.patrick-koglin.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/profile.php?id=61566852463657\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gesetz der Anziehung Archive - Patrick Koglin","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.patrick-koglin.com\/en\/category\/gesetz-der-anziehung\/","og_locale":"en_US","og_type":"article","og_title":"Gesetz der Anziehung Archive - Patrick Koglin","og_url":"https:\/\/www.patrick-koglin.com\/en\/category\/gesetz-der-anziehung\/","og_site_name":"Patrick Koglin","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.patrick-koglin.com\/category\/gesetz-der-anziehung\/","url":"https:\/\/www.patrick-koglin.com\/category\/gesetz-der-anziehung\/","name":"Gesetz der Anziehung Archive - Patrick Koglin","isPartOf":{"@id":"https:\/\/www.patrick-koglin.com\/#website"},"breadcrumb":{"@id":"https:\/\/www.patrick-koglin.com\/category\/gesetz-der-anziehung\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.patrick-koglin.com\/category\/gesetz-der-anziehung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.patrick-koglin.com\/"},{"@type":"ListItem","position":2,"name":"Gesetz der Anziehung"}]},{"@type":"WebSite","@id":"https:\/\/www.patrick-koglin.com\/#website","url":"https:\/\/www.patrick-koglin.com\/","name":"PK Coaching - Patrick Koglin Unternehmensgruppe","description":"PK Coaching, Business-Design &amp; Development","publisher":{"@id":"https:\/\/www.patrick-koglin.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.patrick-koglin.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.patrick-koglin.com\/#organization","name":"Patrick Koglin | CEO von PK Coaching","url":"https:\/\/www.patrick-koglin.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.patrick-koglin.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.patrick-koglin.com\/wp-content\/uploads\/2025\/07\/cropped-PK16.png","contentUrl":"https:\/\/www.patrick-koglin.com\/wp-content\/uploads\/2025\/07\/cropped-PK16.png","width":619,"height":287,"caption":"Patrick Koglin | CEO von PK Coaching"},"image":{"@id":"https:\/\/www.patrick-koglin.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=61566852463657"]}]}},"_links":{"self":[{"href":"https:\/\/www.patrick-koglin.com\/en\/wp-json\/wp\/v2\/categories\/100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.patrick-koglin.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.patrick-koglin.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.patrick-koglin.com\/en\/wp-json\/wp\/v2\/posts?categories=100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}