{"id":6103,"date":"2025-08-13T22:45:29","date_gmt":"2025-08-13T20:45:29","guid":{"rendered":"https:\/\/www.patrick-koglin.com\/?p=6103"},"modified":"2025-08-31T18:05:10","modified_gmt":"2025-08-31T16:05:10","slug":"konkurrenz-ist-toxisch","status":"publish","type":"post","link":"https:\/\/www.patrick-koglin.com\/en\/2025\/08\/konkurrenz-ist-toxisch\/","title":{"rendered":"Konkurrenz ist toxisch \ud83d\udc80 \u2013 und bremst den Erfolg"},"content":{"rendered":"<h3 class=\"wp-block-heading\">St\u00e4ndiger Vergleich<\/h3>\n\n\n\n<p>So viele Menschen \u2013 Gesch\u00e4ftsf\u00fchrer, selbst\u00e4ndige Gr\u00fcnder, F\u00fchrungskr\u00e4fte und Eltern \u2013 denken in Vergleichen: Sie setzen sich st\u00e4ndig in Relation zu ihrem Umfeld.<\/p>\n\n\n\n<p>Wer realisiert die gr\u00f6\u00dferen Projekte? Wer tr\u00e4gt die bessere Kleidung? Wer erzielt mehr Umsatz? Welche Technik bringt den gr\u00f6\u00dften Fortschritt? Wer hat die sch\u00f6nere Wohnung oder ein Haus? Welches Auto ist das bessere? Wer lebt das abwechslungsreichere oder entspanntere Leben?<\/p>\n\n\n\n<p><strong>Lifestyle als Wettbewerb<\/strong><\/p>\n\n\n\n<p>Gerade jetzt, in der Sommersaison, geht es oft darum, wer den besseren, g\u00fcnstigeren, luxuri\u00f6seren oder weiter entfernten Urlaub macht, das tollste Reiseziel gew\u00e4hlt hat oder den sch\u00f6nsten Garten besitzt.<\/p>\n\n\n\n<p>Manchmal auch darum, wer gl\u00fccklicher oder besser gelaunt ist. Menschen und Unternehmen treten in den unterschiedlichsten Aspekten in Konkurrenz zueinander.<\/p>\n\n\n\n<p><strong>Warum Konkurrenzgedanken schaden<\/strong><\/p>\n\n\n\n<p>Jegliche Konkurrenzgedanken sind giftig \u2013 und f\u00fcr Unternehmer oder F\u00fchrungskr\u00e4fte besonders fatal. Sie untergraben die Produktivit\u00e4t, lenken ab und stellen Teams eher gegeneinander, statt sie zusammenzubringen.<\/p>\n\n\n\n<p>Wer konkurriert oder sich von konkurrierenden Menschen beeinflussen l\u00e4sst, ger\u00e4t leicht in emotionale Wettk\u00e4mpfe, die nicht rational, sondern darauf ausgerichtet sind, den anderen zu schw\u00e4chen oder sich selbst besser darzustellen. Bluffer und Player*innen setzen hier gerne auf die \u201eh\u00f6her\u2013schneller\u2013weiter\u2013lauter\u2013besser\u201c-Karte. <\/p>\n\n\n\n<p>Manche Menschen sind nat\u00fcrlich in bestimmten Bereichen erfolgreicher oder besser \u2013 und das ist vollkommen in Ordnung. Entscheidend ist jedoch der Antrieb dahinter und die Wirkung auf andere. Setzt es Menschen unter Druck oder f\u00fchlen sie sich dadurch klein, oder spornt es sie an? All das sind systemische Bewegungen und Effekte, die wir im Blick behalten sollten. <\/p>\n\n\n\n<p>Die Folgen wenn das nicht passiert: weniger gute Handlungen oder Entscheidungen, Abkehr von den eigentlichen Aufgaben und ein gef\u00e4hrliches Verstricken im Wettkampf. Verschwendung in Form von Zeit, Energie und Geld.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Die psychologische Wurzel<\/h3>\n\n\n\n<p>Oft entspringt Konkurrenz einem inneren Mangel \u2013 etwa einem geringen Selbstwertgef\u00fchl oder dem Umstand, dass man seine eigene Einzigartigkeit noch nicht erkannt hat.<\/p>\n\n\n\n<p>In solchen F\u00e4llen wird Konkurrenz zum Mittel, um Neid, Mangelgef\u00fchle oder empfundene Unzul\u00e4nglichkeiten zu kompensieren.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Die Wahrheit: Es gibt gar keine Konkurrenz<\/h2>\n\n\n\n<p>Ob im Business, in der Partnerschaft, unter Freunden, in der Familie oder im Kollegenkreis \u2013 Konkurrenz ist ein mentales Konstrukt und in den meisten F\u00e4llen \u00fcberfl\u00fcssig.<\/p>\n\n\n\n<p>Stell dir vor, du h\u00e4ttest die perfekte Partnerin \/ den besten Partner, den besten Job, das erfolgreichste Team, das passende Wachstum mit idealen Kunden \u2013 genau so, wie du es geplant und erarbeitet hast. Wo w\u00e4re dann noch Platz f\u00fcr Konkurrenz?<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Fokus, Achtsamkeit und Bewusstsein statt Wettbewerb<\/h3>\n\n\n\n<p>Vergleich nach au\u00dfen ist nur dann wertvoll, wenn er dich inspiriert. Wenn jedoch deine Energie und innere St\u00e4rke sinken und du dich klein f\u00fchlst, ist das ein Warnsignal.<\/p>\n\n\n\n<p>Ganz im Gegenteil: Konkurrenz lenkt vom Wesentlichen ab \u2013 von deinen unternehmerischen und pers\u00f6nlichen Zielen.<\/p>\n\n\n\n<p>Mein Tipp: Bleib bei dir. Richte den Fokus auf dein Umfeld, deine eigenen Ziele und grenze dich klar gegen\u00fcber Neidfaktoren und \u00e4u\u00dferen Einfl\u00fcssen ab, die dich in den Wettbewerb ziehen wollen.<\/p>","protected":false},"excerpt":{"rendered":"<p>St\u00e4ndiger Vergleich So viele Menschen \u2013 Gesch\u00e4ftsf\u00fchrer, selbst\u00e4ndige Gr\u00fcnder, F\u00fchrungskr\u00e4fte und Eltern \u2013 denken in Vergleichen: Sie setzen sich st\u00e4ndig in Relation zu ihrem Umfeld. Wer realisiert die gr\u00f6\u00dferen Projekte? Wer tr\u00e4gt die bessere Kleidung? Wer erzielt mehr Umsatz? Welche Technik bringt den gr\u00f6\u00dften Fortschritt? Wer hat die sch\u00f6nere Wohnung oder ein Haus? Welches Auto &#8230; <a title=\"Konkurrenz ist toxisch \ud83d\udc80 \u2013 und bremst den Erfolg\" class=\"read-more\" href=\"https:\/\/www.patrick-koglin.com\/en\/2025\/08\/konkurrenz-ist-toxisch\/\" aria-label=\"Read more about Konkurrenz ist toxisch \ud83d\udc80 \u2013 und bremst den Erfolg\">Read more<\/a><\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-6103","post","type-post","status-publish","format-standard","hentry","category-allgemein"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Konkurrenz ist toxisch \ud83d\udc80 \u2013 und bremst den Erfolg - Patrick Koglin<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.patrick-koglin.com\/en\/2025\/08\/konkurrenz-ist-toxisch\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Konkurrenz ist toxisch \ud83d\udc80 \u2013 und bremst den Erfolg - Patrick Koglin\" \/>\n<meta property=\"og:description\" content=\"St\u00e4ndiger Vergleich So viele Menschen \u2013 Gesch\u00e4ftsf\u00fchrer, selbst\u00e4ndige Gr\u00fcnder, F\u00fchrungskr\u00e4fte und Eltern \u2013 denken in Vergleichen: Sie setzen sich st\u00e4ndig in Relation zu ihrem Umfeld. Wer realisiert die gr\u00f6\u00dferen Projekte? Wer tr\u00e4gt die bessere Kleidung? Wer erzielt mehr Umsatz? Welche Technik bringt den gr\u00f6\u00dften Fortschritt? Wer hat die sch\u00f6nere Wohnung oder ein Haus? Welches Auto ... Read more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.patrick-koglin.com\/en\/2025\/08\/konkurrenz-ist-toxisch\/\" \/>\n<meta property=\"og:site_name\" content=\"Patrick Koglin\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=61566852463657\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-13T20:45:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-31T16:05:10+00:00\" \/>\n<meta name=\"author\" content=\"patrick.koglin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"patrick.koglin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.patrick-koglin.com\/2025\/08\/konkurrenz-ist-toxisch\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.patrick-koglin.com\/2025\/08\/konkurrenz-ist-toxisch\/\"},\"author\":{\"name\":\"patrick.koglin\",\"@id\":\"https:\/\/www.patrick-koglin.com\/#\/schema\/person\/53cba7e1685b1803078bd0bb76d37c0a\"},\"headline\":\"Konkurrenz ist toxisch \ud83d\udc80 \u2013 und bremst den Erfolg\",\"datePublished\":\"2025-08-13T20:45:29+00:00\",\"dateModified\":\"2025-08-31T16:05:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.patrick-koglin.com\/2025\/08\/konkurrenz-ist-toxisch\/\"},\"wordCount\":516,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.patrick-koglin.com\/#organization\"},\"articleSection\":[\"Allgemein\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.patrick-koglin.com\/2025\/08\/konkurrenz-ist-toxisch\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.patrick-koglin.com\/2025\/08\/konkurrenz-ist-toxisch\/\",\"url\":\"https:\/\/www.patrick-koglin.com\/2025\/08\/konkurrenz-ist-toxisch\/\",\"name\":\"Konkurrenz ist toxisch \ud83d\udc80 \u2013 und bremst den Erfolg - Patrick Koglin\",\"isPartOf\":{\"@id\":\"https:\/\/www.patrick-koglin.com\/#website\"},\"datePublished\":\"2025-08-13T20:45:29+00:00\",\"dateModified\":\"2025-08-31T16:05:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.patrick-koglin.com\/2025\/08\/konkurrenz-ist-toxisch\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.patrick-koglin.com\/2025\/08\/konkurrenz-ist-toxisch\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.patrick-koglin.com\/2025\/08\/konkurrenz-ist-toxisch\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.patrick-koglin.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Konkurrenz ist toxisch \ud83d\udc80 \u2013 und bremst den Erfolg\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.patrick-koglin.com\/#website\",\"url\":\"https:\/\/www.patrick-koglin.com\/\",\"name\":\"PK Coaching - Patrick Koglin Unternehmensgruppe\",\"description\":\"PK Coaching, Business-Design &amp; Development\",\"publisher\":{\"@id\":\"https:\/\/www.patrick-koglin.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.patrick-koglin.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.patrick-koglin.com\/#organization\",\"name\":\"Patrick Koglin | CEO von PK Coaching\",\"url\":\"https:\/\/www.patrick-koglin.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.patrick-koglin.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.patrick-koglin.com\/wp-content\/uploads\/2025\/07\/cropped-PK16.png\",\"contentUrl\":\"https:\/\/www.patrick-koglin.com\/wp-content\/uploads\/2025\/07\/cropped-PK16.png\",\"width\":619,\"height\":287,\"caption\":\"Patrick Koglin | CEO von PK Coaching\"},\"image\":{\"@id\":\"https:\/\/www.patrick-koglin.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/profile.php?id=61566852463657\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.patrick-koglin.com\/#\/schema\/person\/53cba7e1685b1803078bd0bb76d37c0a\",\"name\":\"patrick.koglin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.patrick-koglin.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/47ab1c521c62372f70e5d521797d08d2ccccc9b44ffb53bc1b1ac3b0b2844231?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/47ab1c521c62372f70e5d521797d08d2ccccc9b44ffb53bc1b1ac3b0b2844231?s=96&d=mm&r=g\",\"caption\":\"patrick.koglin\"},\"sameAs\":[\"https:\/\/www.patrick-koglin.com\"],\"url\":\"https:\/\/www.patrick-koglin.com\/en\/author\/pkoglin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Konkurrenz ist toxisch \ud83d\udc80 \u2013 und bremst den Erfolg - Patrick Koglin","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.patrick-koglin.com\/en\/2025\/08\/konkurrenz-ist-toxisch\/","og_locale":"en_US","og_type":"article","og_title":"Konkurrenz ist toxisch \ud83d\udc80 \u2013 und bremst den Erfolg - Patrick Koglin","og_description":"St\u00e4ndiger Vergleich So viele Menschen \u2013 Gesch\u00e4ftsf\u00fchrer, selbst\u00e4ndige Gr\u00fcnder, F\u00fchrungskr\u00e4fte und Eltern \u2013 denken in Vergleichen: Sie setzen sich st\u00e4ndig in Relation zu ihrem Umfeld. Wer realisiert die gr\u00f6\u00dferen Projekte? Wer tr\u00e4gt die bessere Kleidung? Wer erzielt mehr Umsatz? Welche Technik bringt den gr\u00f6\u00dften Fortschritt? Wer hat die sch\u00f6nere Wohnung oder ein Haus? Welches Auto ... Read more","og_url":"https:\/\/www.patrick-koglin.com\/en\/2025\/08\/konkurrenz-ist-toxisch\/","og_site_name":"Patrick Koglin","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=61566852463657","article_published_time":"2025-08-13T20:45:29+00:00","article_modified_time":"2025-08-31T16:05:10+00:00","author":"patrick.koglin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"patrick.koglin","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.patrick-koglin.com\/2025\/08\/konkurrenz-ist-toxisch\/#article","isPartOf":{"@id":"https:\/\/www.patrick-koglin.com\/2025\/08\/konkurrenz-ist-toxisch\/"},"author":{"name":"patrick.koglin","@id":"https:\/\/www.patrick-koglin.com\/#\/schema\/person\/53cba7e1685b1803078bd0bb76d37c0a"},"headline":"Konkurrenz ist toxisch \ud83d\udc80 \u2013 und bremst den Erfolg","datePublished":"2025-08-13T20:45:29+00:00","dateModified":"2025-08-31T16:05:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.patrick-koglin.com\/2025\/08\/konkurrenz-ist-toxisch\/"},"wordCount":516,"commentCount":0,"publisher":{"@id":"https:\/\/www.patrick-koglin.com\/#organization"},"articleSection":["Allgemein"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.patrick-koglin.com\/2025\/08\/konkurrenz-ist-toxisch\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.patrick-koglin.com\/2025\/08\/konkurrenz-ist-toxisch\/","url":"https:\/\/www.patrick-koglin.com\/2025\/08\/konkurrenz-ist-toxisch\/","name":"Konkurrenz ist toxisch \ud83d\udc80 \u2013 und bremst den Erfolg - Patrick Koglin","isPartOf":{"@id":"https:\/\/www.patrick-koglin.com\/#website"},"datePublished":"2025-08-13T20:45:29+00:00","dateModified":"2025-08-31T16:05:10+00:00","breadcrumb":{"@id":"https:\/\/www.patrick-koglin.com\/2025\/08\/konkurrenz-ist-toxisch\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.patrick-koglin.com\/2025\/08\/konkurrenz-ist-toxisch\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.patrick-koglin.com\/2025\/08\/konkurrenz-ist-toxisch\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.patrick-koglin.com\/"},{"@type":"ListItem","position":2,"name":"Konkurrenz ist toxisch \ud83d\udc80 \u2013 und bremst den Erfolg"}]},{"@type":"WebSite","@id":"https:\/\/www.patrick-koglin.com\/#website","url":"https:\/\/www.patrick-koglin.com\/","name":"PK Coaching - Patrick Koglin Unternehmensgruppe","description":"PK Coaching, Business-Design &amp; Development","publisher":{"@id":"https:\/\/www.patrick-koglin.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.patrick-koglin.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.patrick-koglin.com\/#organization","name":"Patrick Koglin | CEO von PK Coaching","url":"https:\/\/www.patrick-koglin.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.patrick-koglin.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.patrick-koglin.com\/wp-content\/uploads\/2025\/07\/cropped-PK16.png","contentUrl":"https:\/\/www.patrick-koglin.com\/wp-content\/uploads\/2025\/07\/cropped-PK16.png","width":619,"height":287,"caption":"Patrick Koglin | CEO von PK Coaching"},"image":{"@id":"https:\/\/www.patrick-koglin.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=61566852463657"]},{"@type":"Person","@id":"https:\/\/www.patrick-koglin.com\/#\/schema\/person\/53cba7e1685b1803078bd0bb76d37c0a","name":"patrick.koglin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.patrick-koglin.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/47ab1c521c62372f70e5d521797d08d2ccccc9b44ffb53bc1b1ac3b0b2844231?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/47ab1c521c62372f70e5d521797d08d2ccccc9b44ffb53bc1b1ac3b0b2844231?s=96&d=mm&r=g","caption":"patrick.koglin"},"sameAs":["https:\/\/www.patrick-koglin.com"],"url":"https:\/\/www.patrick-koglin.com\/en\/author\/pkoglin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.patrick-koglin.com\/en\/wp-json\/wp\/v2\/posts\/6103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.patrick-koglin.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.patrick-koglin.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.patrick-koglin.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.patrick-koglin.com\/en\/wp-json\/wp\/v2\/comments?post=6103"}],"version-history":[{"count":11,"href":"https:\/\/www.patrick-koglin.com\/en\/wp-json\/wp\/v2\/posts\/6103\/revisions"}],"predecessor-version":[{"id":7106,"href":"https:\/\/www.patrick-koglin.com\/en\/wp-json\/wp\/v2\/posts\/6103\/revisions\/7106"}],"wp:attachment":[{"href":"https:\/\/www.patrick-koglin.com\/en\/wp-json\/wp\/v2\/media?parent=6103"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.patrick-koglin.com\/en\/wp-json\/wp\/v2\/categories?post=6103"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.patrick-koglin.com\/en\/wp-json\/wp\/v2\/tags?post=6103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}